{"id":14292,"date":"2023-05-02T09:31:12","date_gmt":"2023-05-02T09:31:12","guid":{"rendered":"https:\/\/staging.registrarcorp.com\/values\/"},"modified":"2024-09-27T14:36:37","modified_gmt":"2024-09-27T14:36:37","slug":"values","status":"publish","type":"page","link":"https:\/\/staging.registrarcorp.com\/it\/about-us\/values\/","title":{"rendered":"Valori"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1726759459906{padding-top: 70px !important;background-color: #ffffff !important;}&#8221; el_class=&#8221;vertical-text-align hero-section&#8221;][vc_column width=&#8221;2\/3&#8243; el_class=&#8221;col-txt-center&#8221;][vc_custom_heading text=&#8221;I nostri valori&#8221; font_container=&#8221;tag:h1|font_size:56px|text_align:left|color:%23003873&#8243; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221;][vc_column_text fnt_family=&#8221;Montserrat&#8221; fnt_size=&#8221;24px&#8221;]I nostri valori sono ci\u00f2 che ci plasma davvero come azienda. Definiscono chi siamo, come lavoriamo e come assumiamo. Il nostro obiettivo \u00e8 creare un ambiente di lavoro incentrato sulle persone in cui tutti siano entusiasti di risolvere i problemi, condividere idee e imparare qualcosa di nuovo ogni giorno.[\/vc_column_text][vc_btn title=&#8221;Unisciti al nostro team&#8221; style=&#8221;flat&#8221; shape=&#8221;square&#8221; color=&#8221;blue&#8221; align=&#8221;left&#8221; i_align=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-arrow-right&#8221; add_icon=&#8221;true&#8221; el_class=&#8221;primary-btn&#8221; link=&#8221;url:https%3A%2F%2Fstaging.registrarcorp.com%2Fit%2Fcareers%2F|&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;985&#8243; img_size=&#8221;515&#215;540&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1688798363515{padding-top: 50px !important;padding-bottom: 50px !important;background-color: #ffffff !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;993&#8243; img_size=&#8221;500&#215;710&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Le persone prima di tutto.&#8221; font_container=&#8221;tag:h2|font_size:40px|text_align:left|color:%23003873&#8243; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1692034413379{padding-top: 46px !important;}&#8221; fnt_family=&#8221;Montserrat&#8221; fnt_size=&#8221;18px&#8221;]Dipendenti felici significano clienti pi\u00f9 felici. Crediamo che le aziende di successo siano costruite sulle persone, ed \u00e8 per questo che siamo profondamente motivati ad avere un impatto positivo sulla vita dei nostri dipendenti, in modo che apprezzino il lavoro che svolgono.[\/vc_column_text][vc_custom_heading text=&#8221;Risolvi, migliora, ripeti.&#8221; font_container=&#8221;tag:h2|font_size:40px|text_align:left|color:%23003873&#8243; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1692034425120{padding-top: 46px !important;}&#8221; fnt_family=&#8221;Montserrat&#8221; fnt_size=&#8221;18px&#8221;]Affrontiamo i problemi difficili con curiosit\u00e0 e determinazione. Invece di affrettarci a risolvere una risposta e andare avanti, consideriamo ogni sfida un\u2019opportunit\u00e0 per esaminare come lavoriamo, perfezionare il nostro approccio e migliorare continuamente.[\/vc_column_text][vc_custom_heading text=&#8221;Servire attraverso l\u2019innovazione.&#8221; font_container=&#8221;tag:h2|font_size:40px|text_align:left|color:%23003873&#8243; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1692034435794{padding-top: 46px !important;}&#8221; fnt_family=&#8221;Montserrat&#8221; fnt_size=&#8221;18px&#8221;]Siamo motivati a servire i nostri clienti attraverso prodotti e servizi di conformit\u00e0 innovativi e leader del settore. Lo facciamo apprendendo costantemente i nostri settori e rimanendo al passo con i nuovi sviluppi normativi e tecnologici.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1688798091768{background-color: #a5dbff !important;}&#8221; el_class=&#8221;vertical-text-align&#8221;][vc_column width=&#8221;2\/3&#8243; el_class=&#8221;col-txt-center&#8221;][vc_custom_heading text=&#8221;Vuoi lavorare con noi?&#8221; font_container=&#8221;tag:h2|font_size:40|text_align:left|color:%23003873&#8243; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][vc_column_text fnt_family=&#8221;Montserrat&#8221; fnt_size=&#8221;18px&#8221;]Con valori forti e incentrati sulle persone e la missione di rendere la catena di fornitura pi\u00f9 sicura, Registrar Corp \u00e8 un ottimo luogo di lavoro. Scopri le nostre ultime offerte di lavoro.[\/vc_column_text][vc_btn title=&#8221;Unisciti al nostro team&#8221; style=&#8221;flat&#8221; shape=&#8221;square&#8221; color=&#8221;blue&#8221; align=&#8221;left&#8221; i_align=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-arrow-right&#8221; add_icon=&#8221;true&#8221; el_class=&#8221;primary-btn&#8221; link=&#8221;url:https%3A%2F%2Fstaging.registrarcorp.com%2Fit%2Fcareers%2F|&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;1105&#8243; img_size=&#8221;515&#215;540&#8243;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1726759459906{padding-top: 70px !important;background-color: #ffffff !important;}&#8221; el_class=&#8221;vertical-text-align hero-section&#8221;][vc_column width=&#8221;2\/3&#8243; el_class=&#8221;col-txt-center&#8221;][vc_custom_heading text=&#8221;I nostri valori&#8221; font_container=&#8221;tag:h1|font_size:56px|text_align:left|color:%23003873&#8243; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221;][vc_column_text fnt_family=&#8221;Montserrat&#8221; fnt_size=&#8221;24px&#8221;]I nostri valori sono ci\u00f2 che ci plasma davvero come azienda. Definiscono chi siamo, come lavoriamo e come assumiamo. Il nostro obiettivo \u00e8 creare un ambiente di lavoro incentrato sulle persone in cui tutti siano entusiasti di risolvere<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":14896,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page-sidebar-none.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-14292","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/pages\/14292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/comments?post=14292"}],"version-history":[{"count":0,"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/pages\/14292\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/pages\/14896"}],"wp:attachment":[{"href":"https:\/\/staging.registrarcorp.com\/it\/wp-json\/wp\/v2\/media?parent=14292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}